{"id":4456,"date":"2024-05-22T09:47:02","date_gmt":"2024-05-22T07:47:02","guid":{"rendered":"https:\/\/michaelfuchs.com\/imprint\/"},"modified":"2026-07-09T19:33:09","modified_gmt":"2026-07-09T17:33:09","slug":"imprint","status":"publish","type":"page","link":"https:\/\/michaelfuchs.com\/en\/imprint\/","title":{"rendered":"Imprint"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4456\" class=\"elementor elementor-4456 elementor-94\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42e32ba6 e-flex e-con-boxed e-con e-parent\" data-id=\"42e32ba6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48bb0a4 e-con-full e-flex e-con e-child\" data-id=\"48bb0a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb693a8 elementor-widget elementor-widget-heading\" data-id=\"fb693a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Impressum<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b48ba elementor-widget elementor-widget-spacer\" data-id=\"e3b48ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e46e834 elementor-widget elementor-widget-text-editor\" data-id=\"2e46e834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<div  class=\"agb_content agb_imprint  notranslate\"><div>Michael Fuchs<br \/>\nAn der Schiessst&auml;tte 4<br \/>\n87509 Immenstadt<br \/>\nDeutschland<br \/>\n<br \/>\nTel.: 00491622769128<br \/>\nE-Mail: info@michaelfuchs.com<br \/>\n<br \/>\nVerantwortliche\/r i.S.d. &sect; 18 Abs. 2 MStV:<br \/>\nMichael Fuchs, An der Schiessst&auml;tte 4, 87509 Immenstadt<br \/>\n<br \/>\nWir sind zur Teilnahme an einem Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle weder verpflichtet noch bereit.<\/div><div id=\"itkanzlei_txt_copyright\" style=\"font-size: 12px; margin-top: 8em;\"><div style=\"display: inline-block; vertical-align: top; margin-left: 5px; float: right; white-space: nowrap;\">Stand: 09.07.2026, 19:33:07<\/div><div style=\"clear: right;\"><\/div><\/div><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4456","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/pages\/4456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/comments?post=4456"}],"version-history":[{"count":1,"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/pages\/4456\/revisions"}],"predecessor-version":[{"id":4457,"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/pages\/4456\/revisions\/4457"}],"wp:attachment":[{"href":"https:\/\/michaelfuchs.com\/en\/wp-json\/wp\/v2\/media?parent=4456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}